{"id":85,"count":2,"description":"166, 495","link":"https:\/\/shengmingshige.net\/blog\/tag\/carter-r-kelso","name":"Carter\uff0c R. Kelso","slug":"carter-r-kelso","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/shengmingshige.net\/blog\/wp-json\/wp\/v2\/tags\/85"}],"collection":[{"href":"https:\/\/shengmingshige.net\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/shengmingshige.net\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/shengmingshige.net\/blog\/wp-json\/wp\/v2\/posts?tags=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}